{"id":261053,"date":"2026-01-21T09:06:55","date_gmt":"2026-01-21T14:06:55","guid":{"rendered":"https:\/\/ugel04.gob.pe\/home\/?p=261053"},"modified":"2026-05-11T11:16:04","modified_gmt":"2026-05-11T16:16:04","slug":"directivos-y-docentes-de-47-colegios-publicos-se-capacitan-con-samsung-en-pizarras-interactivas","status":"publish","type":"post","link":"https:\/\/ugel04.gob.pe\/home\/directivos-y-docentes-de-47-colegios-publicos-se-capacitan-con-samsung-en-pizarras-interactivas\/","title":{"rendered":"DIRECTIVOS Y DOCENTES DE 47 COLEGIOS P\u00daBLICOS SE CAPACITAN CON SAMSUNG EN PIZARRAS INTERACTIVAS"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb da_disable_devices=\u00bboff|off|off\u00bb][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><strong>La UGEL 04, en coordinaci\u00f3n con la empresa Samsung, capacit\u00f3 a directivos y docentes de Innovaci\u00f3n Pedag\u00f3gica (PIP) de 47 instituciones educativas p\u00fablicas del nivel secundario, beneficiarias de pantallas interactivas de \u00faltima generaci\u00f3n, como parte del impulso a la innovaci\u00f3n educativa de nuestra jurisdicci\u00f3n.<\/strong><\/p>\n<p>Durante la jornada, los participantes fortalecieron competencias pr\u00e1cticas para el uso pedag\u00f3gico de estos recursos tecnol\u00f3gicos, fundamentales para el soporte y acompa\u00f1amiento digital en las instituciones educativas. La capacitaci\u00f3n estuvo a cargo de un especialista de Samsung, quien explic\u00f3 el manejo y las principales funcionalidades de las pantallas inteligentes.<\/p>\n<p>Estos equipos, de 86 pulgadas y resoluci\u00f3n 4K Ultra HD, permiten visualizar contenidos, reproducir material audiovisual y elaborar recursos digitales, favoreciendo clases m\u00e1s din\u00e1micas y participativas. Al finalizar, los docentes reafirmaron su compromiso de fortalecer los aprendizajes de los estudiantes mediante el uso de la tecnolog\u00eda.<\/p>\n<p>La actividad se realiz\u00f3 en la IE 2100 Juan Velasco Alvarado, en el distrito de Comas, y cont\u00f3 con la presencia de la directora de la UGEL 04, Nelly Cunza Pr\u00edncipe, el jefe de AGEBRE, Jhonny Ventura y especialistas del \u00e1rea, quienes destacaron que esta iniciativa contribuir\u00e1 a mejorar la experiencia de aprendizaje y responder a las demandas actuales del sistema educativo. Asimismo, resaltaron que la entrega de las 47 pizarras inteligentes se realiz\u00f3 con recursos propios, como parte de la apuesta institucional por la modernizaci\u00f3n educativa.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La UGEL 04, en coordinaci\u00f3n con la empresa Samsung, capacit\u00f3 a directivos y docentes de Innovaci\u00f3n Pedag\u00f3gica (PIP) de 47 instituciones educativas p\u00fablicas del nivel secundario, beneficiarias de pantallas interactivas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":261054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-261053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/posts\/261053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/comments?post=261053"}],"version-history":[{"count":2,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/posts\/261053\/revisions"}],"predecessor-version":[{"id":261057,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/posts\/261053\/revisions\/261057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/media\/261054"}],"wp:attachment":[{"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/media?parent=261053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/categories?post=261053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/tags?post=261053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}