{"id":246890,"date":"2022-10-21T21:11:00","date_gmt":"2022-10-21T21:11:00","guid":{"rendered":"https:\/\/ugel04.gob.pe\/home\/?p=246890"},"modified":"2026-05-11T11:13:26","modified_gmt":"2026-05-11T16:13:26","slug":"instituciones-aliadas-apoyan-etapa-final-de-juegos-escolares-deportivos","status":"publish","type":"post","link":"https:\/\/ugel04.gob.pe\/home\/instituciones-aliadas-apoyan-etapa-final-de-juegos-escolares-deportivos\/","title":{"rendered":"INSTITUCIONES ALIADAS APOYAN ETAPA FINAL DE JUEGOS ESCOLARES DEPORTIVOS"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Diversas instituciones p\u00fablicas y privadas han sumado su apoyo a los Juegos Escolares Deportivos y Paradeportivos que organiza el Ministerio de Educaci\u00f3n (Minedu) y cuya etapa final se desarrollar\u00e1 en Lima entre el 24 y el 28 de octubre con la participaci\u00f3n de 1200 escolares de todo el pa\u00eds.<br \/>En respuesta a la invitaci\u00f3n hecha por el Minedu, estas instituciones aliadas contribuir\u00e1n a la realizaci\u00f3n de la etapa nacional en diferentes aspectos, como el pr\u00e9stamo de infraestructura, apoyo en alimentaci\u00f3n e hidrataci\u00f3n y la difusi\u00f3n de las competencias.<br \/>As\u00ed, instituciones como Legado, Universidad de Lima y los colegios Bartolom\u00e9 Herrera y Ricardo Palma pondr\u00e1n a disposici\u00f3n sus instalaciones para el desarrollo de las competencias.<br \/>De igual forma, las empresas Arca Continental Lindley y The Central Am\u00e9rica Bottling Corporation (CBC Per\u00fa) suministrar\u00e1n agua y bebidas hidratantes a los competidores.<br \/>Asimismo, el fundador de la empresa Nutri H, Julio Garay Barrios, apoyar\u00e1 con la entrega de\u00a0 galletas Nutri \u201cH\u201d, que buscan mejorar la alimentaci\u00f3n de la poblaci\u00f3n reduciendo los \u00edndices de anemia y desnutrici\u00f3n infantil.<br \/>El certamen tambi\u00e9n contar\u00e1 con el apoyo de Editora Per\u00fa a trav\u00e9s del diario El Peruano y la Agencia de Noticias Andina. Como en versiones anteriores, la Agencia de Noticias Andina ser\u00e1 la agencia oficial de los Juegos Escolares Deportivos y Paradeportivos.\u00a0<br \/>En la difusi\u00f3n de esta gran fiesta deportiva tambi\u00e9n colaboran la Asociaci\u00f3n Deportiva de F\u00fatbol Profesional, el Instituto Nacional de Radio y Televisi\u00f3n del Per\u00fa (IRTP) y Movistar Deportes, as\u00ed como JMT Outdoors con avisos publicitarios en diferentes puntos de Lima.<br \/>Las competencias de la etapa final se realizar\u00e1n en cinco escenarios entre las 8 a.m. y las 4:30 p.m. del lunes 24 al viernes 28 de octubre. El ingreso es libre.<\/p>\n<p>SEDES<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Legado Videna de San Luis (atletismo, paraatletismo, nataci\u00f3n, judo, ajedrez, handball y tenis de mesa)<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Centro Pre Universitario de la Universidad de Lima (futsal, futbol damas y b\u00e1squet)<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Legado de Villa El Salvador (voleibol)<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 I.E. Bartolom\u00e9 Herrrera (futbol pueblos originarios)<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 I.E. Ricardo Palma (futbol de varones)<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Diversas instituciones p\u00fablicas y privadas han sumado su apoyo a los Juegos Escolares Deportivos y Paradeportivos que organiza el Ministerio de Educaci\u00f3n (Minedu) y cuya etapa final se desarrollar\u00e1 en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":246891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"1080","footnotes":""},"categories":[1],"tags":[],"class_list":["post-246890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/posts\/246890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/comments?post=246890"}],"version-history":[{"count":3,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/posts\/246890\/revisions"}],"predecessor-version":[{"id":246894,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/posts\/246890\/revisions\/246894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/media\/246891"}],"wp:attachment":[{"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/media?parent=246890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/categories?post=246890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ugel04.gob.pe\/home\/wp-json\/wp\/v2\/tags?post=246890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}